{"id":1,"count":1,"description":"","link":"http:\/\/www.moderaco.com\/index.php\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.moderaco.com\/index.php\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.moderaco.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.moderaco.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.moderaco.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}